{"id":64,"count":1,"description":"","link":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/","name":"red awareness ribbon gifts","slug":"red-awareness-ribbon-gifts","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>red awareness ribbon gifts Archives - Awareness Gallery Art<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"red awareness ribbon gifts Archives - Awareness Gallery Art\" \/>\n<meta property=\"og:url\" content=\"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/\" \/>\n<meta property=\"og:site_name\" content=\"Awareness Gallery Art\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/tag\\\/red-awareness-ribbon-gifts\\\/\",\"url\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/tag\\\/red-awareness-ribbon-gifts\\\/\",\"name\":\"red awareness ribbon gifts Archives - Awareness Gallery Art\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/tag\\\/red-awareness-ribbon-gifts\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/tag\\\/red-awareness-ribbon-gifts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"red awareness ribbon gifts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/\",\"name\":\"Awareness Gallery Art\",\"description\":\"Featuring the Art of Awareness Ribbons\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/awarenessgallery.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"red awareness ribbon gifts Archives - Awareness Gallery Art","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/","og_locale":"en_US","og_type":"article","og_title":"red awareness ribbon gifts Archives - Awareness Gallery Art","og_url":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/","og_site_name":"Awareness Gallery Art","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/","url":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/","name":"red awareness ribbon gifts Archives - Awareness Gallery Art","isPartOf":{"@id":"https:\/\/awarenessgallery.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/awarenessgallery.com\/blog\/tag\/red-awareness-ribbon-gifts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/awarenessgallery.com\/blog\/"},{"@type":"ListItem","position":2,"name":"red awareness ribbon gifts"}]},{"@type":"WebSite","@id":"https:\/\/awarenessgallery.com\/blog\/#website","url":"https:\/\/awarenessgallery.com\/blog\/","name":"Awareness Gallery Art","description":"Featuring the Art of Awareness Ribbons","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/awarenessgallery.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/awarenessgallery.com\/blog\/wp-json\/wp\/v2\/tags\/64","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awarenessgallery.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/awarenessgallery.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/awarenessgallery.com\/blog\/wp-json\/wp\/v2\/posts?tags=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}